{"id":813,"date":"2026-05-11T10:22:16","date_gmt":"2026-05-11T13:22:16","guid":{"rendered":"https:\/\/mambiente.cambe.pr.gov.br\/?p=813"},"modified":"2026-05-11T10:22:16","modified_gmt":"2026-05-11T13:22:16","slug":"cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem","status":"publish","type":"post","link":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/","title":{"rendered":"Cronograma Semanal (11\/05 a 15\/05) de Coleta de Res\u00edduos Volumosos e de Jardinagem"},"content":{"rendered":"<p>Res\u00edduos volumosos ou de descarte incomum s\u00e3o aqueles que, devido \u00e0s suas dimens\u00f5es ou caracter\u00edsticas espec\u00edficas, n\u00e3o podem ser acondicionados em sacos pl\u00e1sticos convencionais. Esta categoria compreende itens como m\u00f3veis inserv\u00edveis, sucatas, galhos e restos de podas de \u00e1rvores ou arbustos.<\/p>\n<p>Para que a coleta seja efetuada, o volume total n\u00e3o deve exceder 01 (um) metro c\u00fabico (1 m\u00b3), em estrita observ\u00e2ncia \u00e0 legisla\u00e7\u00e3o municipal vigente.<\/p>\n<p>\u00c9 importante evitar o descarte irregular desses res\u00edduos, pois isso pode causar problemas ambientais e prejudicar a limpeza urbana. Seguindo o cronograma estabelecido, contribu\u00edmos para a manuten\u00e7\u00e3o de um ambiente mais limpo e saud\u00e1vel para todos.<\/p>\n<p><strong>Cronograma Semanal (11\/05 a 15\/05) de Coleta de Res\u00edduos Volumosos e\u00a0 de Jardinagem.<\/strong><\/p>\n<p><em>Regi\u00e3o do Novo Bandeirantes<\/em><br \/>\nAs duas equipes iniciar\u00e3o no Jd. Novo Bandeirantes, seguem para o Jd. Ana Eliza I, Silvino, Ana Eliza III, Morumbi, \u00c1gua da Esperan\u00e7a, Ecoville, Camb\u00e9ville, Barrada, Campos Verdes, \u00a0Jardim Riviera e Montecatini.<\/p>\n<p><em>Regi\u00e3o do Santo Amaro<\/em><br \/>\nEquipe 1: Iniciar\u00e3o no Jd. Monte Castelo, seguem para o Jd. S\u00e3o Caetano, Jd. Santo Andr\u00e9, Santo Amaro e S\u00e3o Paulo.<br \/>\nEquipe 2: Iniciar\u00e3o no Jd. Bela It\u00e1lia, seguem para o Jd. Bela Sui\u00e7a,Caf\u00e9 II, Boa Vista,\u00a0Pq. Manela, Manelinha e Jd Uni\u00e3o.<\/p>\n<p><em>Regi\u00e3o do Ana Rosa<\/em><br \/>\nEquipe 1: Iniciar\u00e3o no Jd. Tupi, seguem para o Jd. Jos\u00e9 Favaro.<br \/>\nEquipe 2: Iniciar\u00e3o na Jd Camb\u00e9 V, seguem para Jd Ulisses Guimar\u00e3es.<\/p>\n<p><em>Regi\u00e3o Central<br \/>\n<\/em>Equipe 1: Avenidas e travessas do centro.<br \/>\nEquipe 2: Iniciar\u00e3o no Jd. Santa Helena, seguem para o Jd. Nestor Ferrari, Morada do Sol, Portal do Lago, Vila Salom\u00e9 e V\u00f4 Zezinho.<br \/>\nEquipe 3: Iniciar\u00e3o no Jd.Camb\u00e9 II, seguem para o Jd. Vila Rica, Santa Izabel, Morumbi e Maria Flora.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-814\" src=\"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6.jpg\" alt=\"\" width=\"1600\" height=\"900\" srcset=\"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6.jpg 1600w, https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6-300x169.jpg 300w, https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6-1024x576.jpg 1024w, https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6-768x432.jpg 768w, https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Res\u00edduos volumosos ou de descarte incomum s\u00e3o aqueles que, devido \u00e0s suas dimens\u00f5es ou caracter\u00edsticas espec\u00edficas, n\u00e3o podem ser acondicionados em sacos pl\u00e1sticos convencionais. Esta categoria compreende itens como m\u00f3veis inserv\u00edveis, sucatas, galhos e restos de podas de \u00e1rvores ou arbustos. Para que a coleta seja efetuada, o volume total n\u00e3o deve exceder 01 (um) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-813","post","type-post","status-publish","format-standard","hentry","category-principal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cronograma Semanal (11\/05 a 15\/05) de Coleta de Res\u00edduos Volumosos e de Jardinagem - Secretaria de Agricultura e Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cronograma Semanal (11\/05 a 15\/05) de Coleta de Res\u00edduos Volumosos e de Jardinagem - Secretaria de Agricultura e Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Res\u00edduos volumosos ou de descarte incomum s\u00e3o aqueles que, devido \u00e0s suas dimens\u00f5es ou caracter\u00edsticas espec\u00edficas, n\u00e3o podem ser acondicionados em sacos pl\u00e1sticos convencionais. Esta categoria compreende itens como m\u00f3veis inserv\u00edveis, sucatas, galhos e restos de podas de \u00e1rvores ou arbustos. Para que a coleta seja efetuada, o volume total n\u00e3o deve exceder 01 (um) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Agricultura e Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T13:22:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Departamento T\u00e9cnico Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Departamento T\u00e9cnico Ambiental\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/\"},\"author\":{\"name\":\"Departamento T\u00e9cnico Ambiental\",\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/#\/schema\/person\/39541189ab61662ac71828c6306bc6fb\"},\"headline\":\"Cronograma Semanal (11\/05 a 15\/05) de Coleta de Res\u00edduos Volumosos e de Jardinagem\",\"datePublished\":\"2026-05-11T13:22:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/\"},\"wordCount\":315,\"publisher\":{\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6.jpg\",\"articleSection\":[\"Principal\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/\",\"url\":\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/\",\"name\":\"Cronograma Semanal (11\/05 a 15\/05) de Coleta de Res\u00edduos Volumosos e de Jardinagem - Secretaria de Agricultura e Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6.jpg\",\"datePublished\":\"2026-05-11T13:22:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/#primaryimage\",\"url\":\"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6.jpg\",\"contentUrl\":\"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mambiente.cambe.pr.gov.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cronograma Semanal (11\/05 a 15\/05) de Coleta de Res\u00edduos Volumosos e de Jardinagem\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/#website\",\"url\":\"https:\/\/mambiente.cambe.pr.gov.br\/\",\"name\":\"Secretaria de Agricultura e Meio Ambiente\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mambiente.cambe.pr.gov.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/#organization\",\"name\":\"Secretaria de Agricultura e Meio Ambiente\",\"url\":\"https:\/\/mambiente.cambe.pr.gov.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2024\/01\/brasao_cambe.png\",\"contentUrl\":\"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2024\/01\/brasao_cambe.png\",\"width\":600,\"height\":600,\"caption\":\"Secretaria de Agricultura e Meio Ambiente\"},\"image\":{\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/#\/schema\/person\/39541189ab61662ac71828c6306bc6fb\",\"name\":\"Departamento T\u00e9cnico Ambiental\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/mambiente.cambe.pr.gov.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/litespeed\/avatar\/cee861194c0a71b558d37d0e50f2e695.jpg?ver=1778094405\",\"contentUrl\":\"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/litespeed\/avatar\/cee861194c0a71b558d37d0e50f2e695.jpg?ver=1778094405\",\"caption\":\"Departamento T\u00e9cnico Ambiental\"},\"url\":\"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/author\/tbvidovix\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cronograma Semanal (11\/05 a 15\/05) de Coleta de Res\u00edduos Volumosos e de Jardinagem - Secretaria de Agricultura e Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/","og_locale":"pt_BR","og_type":"article","og_title":"Cronograma Semanal (11\/05 a 15\/05) de Coleta de Res\u00edduos Volumosos e de Jardinagem - Secretaria de Agricultura e Meio Ambiente","og_description":"Res\u00edduos volumosos ou de descarte incomum s\u00e3o aqueles que, devido \u00e0s suas dimens\u00f5es ou caracter\u00edsticas espec\u00edficas, n\u00e3o podem ser acondicionados em sacos pl\u00e1sticos convencionais. Esta categoria compreende itens como m\u00f3veis inserv\u00edveis, sucatas, galhos e restos de podas de \u00e1rvores ou arbustos. Para que a coleta seja efetuada, o volume total n\u00e3o deve exceder 01 (um) [&hellip;]","og_url":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/","og_site_name":"Secretaria de Agricultura e Meio Ambiente","article_published_time":"2026-05-11T13:22:16+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6.jpg","type":"image\/jpeg"}],"author":"Departamento T\u00e9cnico Ambiental","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Departamento T\u00e9cnico Ambiental","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/#article","isPartOf":{"@id":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/"},"author":{"name":"Departamento T\u00e9cnico Ambiental","@id":"https:\/\/mambiente.cambe.pr.gov.br\/#\/schema\/person\/39541189ab61662ac71828c6306bc6fb"},"headline":"Cronograma Semanal (11\/05 a 15\/05) de Coleta de Res\u00edduos Volumosos e de Jardinagem","datePublished":"2026-05-11T13:22:16+00:00","mainEntityOfPage":{"@id":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/"},"wordCount":315,"publisher":{"@id":"https:\/\/mambiente.cambe.pr.gov.br\/#organization"},"image":{"@id":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/#primaryimage"},"thumbnailUrl":"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6.jpg","articleSection":["Principal"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/","url":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/","name":"Cronograma Semanal (11\/05 a 15\/05) de Coleta de Res\u00edduos Volumosos e de Jardinagem - Secretaria de Agricultura e Meio Ambiente","isPartOf":{"@id":"https:\/\/mambiente.cambe.pr.gov.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/#primaryimage"},"image":{"@id":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/#primaryimage"},"thumbnailUrl":"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6.jpg","datePublished":"2026-05-11T13:22:16+00:00","breadcrumb":{"@id":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/#primaryimage","url":"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6.jpg","contentUrl":"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2026\/05\/462e654e-0039-47f9-bea3-3d8dcc7da6e6.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/cronograma-semanal-11-05-a-15-05-de-coleta-de-residuos-volumosos-e-de-jardinagem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mambiente.cambe.pr.gov.br\/"},{"@type":"ListItem","position":2,"name":"Cronograma Semanal (11\/05 a 15\/05) de Coleta de Res\u00edduos Volumosos e de Jardinagem"}]},{"@type":"WebSite","@id":"https:\/\/mambiente.cambe.pr.gov.br\/#website","url":"https:\/\/mambiente.cambe.pr.gov.br\/","name":"Secretaria de Agricultura e Meio Ambiente","description":"","publisher":{"@id":"https:\/\/mambiente.cambe.pr.gov.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mambiente.cambe.pr.gov.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mambiente.cambe.pr.gov.br\/#organization","name":"Secretaria de Agricultura e Meio Ambiente","url":"https:\/\/mambiente.cambe.pr.gov.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mambiente.cambe.pr.gov.br\/#\/schema\/logo\/image\/","url":"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2024\/01\/brasao_cambe.png","contentUrl":"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/uploads\/2024\/01\/brasao_cambe.png","width":600,"height":600,"caption":"Secretaria de Agricultura e Meio Ambiente"},"image":{"@id":"https:\/\/mambiente.cambe.pr.gov.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mambiente.cambe.pr.gov.br\/#\/schema\/person\/39541189ab61662ac71828c6306bc6fb","name":"Departamento T\u00e9cnico Ambiental","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mambiente.cambe.pr.gov.br\/#\/schema\/person\/image\/","url":"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/litespeed\/avatar\/cee861194c0a71b558d37d0e50f2e695.jpg?ver=1778094405","contentUrl":"https:\/\/mambiente.cambe.pr.gov.br\/wp-content\/litespeed\/avatar\/cee861194c0a71b558d37d0e50f2e695.jpg?ver=1778094405","caption":"Departamento T\u00e9cnico Ambiental"},"url":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/author\/tbvidovix\/"}]}},"_links":{"self":[{"href":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/comments?post=813"}],"version-history":[{"count":1,"href":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/813\/revisions"}],"predecessor-version":[{"id":815,"href":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/813\/revisions\/815"}],"wp:attachment":[{"href":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/media?parent=813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/categories?post=813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mambiente.cambe.pr.gov.br\/index.php\/wp-json\/wp\/v2\/tags?post=813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}